{"id":10815,"date":"2026-07-14T11:57:23","date_gmt":"2026-07-14T14:57:23","guid":{"rendered":"https:\/\/www.cbnrecife.com\/blogdoelielson\/2026\/07\/14\/sertania-com-apoio-do-governo-do-estado-avanca-com-obras-de-pavimentacao-e-asfaltamento-em-ruas-da-sede-e-dos-distritos\/"},"modified":"2026-07-14T11:57:29","modified_gmt":"2026-07-14T14:57:29","slug":"sertania-com-apoio-do-governo-do-estado-avanca-com-obras-de-pavimentacao-e-asfaltamento-em-ruas-da-sede-e-dos-distritos","status":"publish","type":"post","link":"https:\/\/www.cbnrecife.com\/blogdoelielson\/2026\/07\/14\/sertania-com-apoio-do-governo-do-estado-avanca-com-obras-de-pavimentacao-e-asfaltamento-em-ruas-da-sede-e-dos-distritos\/","title":{"rendered":"Sert\u00e2nia com apoio do Governo do Estado avan\u00e7a com obras de pavimenta\u00e7\u00e3o e asfaltamento em ruas da sede e dos distritos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Prefeitura de Sert\u00e2nia segue ampliando os investimentos em infraestrutura urbana, com obras de pavimenta\u00e7\u00e3o e asfaltamento em diversos bairros da cidade. Desta vez, a tradicional Rua Imaculada Concei\u00e7\u00e3o est\u00e1 recebendo pavimenta\u00e7\u00e3o asf\u00e1ltica, atendendo a um antigo sonho dos moradores e proporcionando mais mobilidade, seguran\u00e7a e qualidade de vida para a popula\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As obras tamb\u00e9m contemplam outras importantes vias, como as ruas da Saudade e Arcoverde, e seguem avan\u00e7ando para os bairros M\u00e1rio Melo Nova e Alto do Cemit\u00e9rio. O objetivo da gest\u00e3o municipal \u00e9 garantir uma malha vi\u00e1ria cada vez mais moderna e acess\u00edvel, facilitando o deslocamento de moradores e visitantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A prefeita Pollyanna Abreu destacou que o cronograma de obras continuar\u00e1 beneficiando outras ruas da sede, al\u00e9m dos distritos e povoados do munic\u00edpio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Nosso compromisso \u00e9 levar pavimenta\u00e7\u00e3o e asfalto para todas as localidades de Sert\u00e2nia. At\u00e9 o fim deste semestre, teremos diversas obras sendo conclu\u00eddas e outras anunciadas. Queremos transformar nossas ruas em verdadeiros tapetes, oferecendo mais conforto, seguran\u00e7a e dignidade para a popula\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fazemos festas, mas nossa maior responsabilidade \u00e9 trabalhar e entregar obras que melhorem a vida das pessoas. Com o apoio do Governo de Pernambuco, continuaremos buscando mais investimentos para o desenvolvimento do nosso munic\u00edpio&#8221;, afirmou a prefeita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Sert\u00e2nia segue ampliando os investimentos em infraestrutura urbana, com obras de pavimenta\u00e7\u00e3o e asfaltamento em diversos bairros da cidade. Desta vez, a tradicional Rua Imaculada Concei\u00e7\u00e3o est\u00e1 recebendo pavimenta\u00e7\u00e3o asf\u00e1ltica, atendendo a um antigo sonho dos moradores e proporcionando mais mobilidade, seguran\u00e7a e qualidade de vida para a popula\u00e7\u00e3o. As obras tamb\u00e9m [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":10814,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_eb_attr":"","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[64],"tags":[],"ppma_author":[40],"class_list":["post-10815","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"author_meta":{"display_name":"Jo\u00e3o Durant","author_link":"https:\/\/www.cbnrecife.com\/blogdoelielson\/author\/joaodurant\/"},"featured_img":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.45.44-170x300.jpeg","coauthors":[{"link":"https:\/\/www.cbnrecife.com\/blogdoelielson\/author\/joaodurant\/","display_name":"Jo\u00e3o Durant"}],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.cbnrecife.com\/blogdoelielson\/category\/politica\/\" class=\"advgb-post-tax-term\">Pol\u00edtica<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Pol\u00edtica<\/span>"]}},"comment_count":0,"relative_dates":{"created":"Publicado 18 horas atr\u00e1s","modified":"Atualizado 18 horas atr\u00e1s"},"absolute_dates":{"created":"Publicado em 14\/07\/2026","modified":"Atualizado em 14\/07\/2026"},"absolute_dates_time":{"created":"Publicado em 14\/07\/2026 11:57","modified":"Atualizado em 14\/07\/2026 11:57"},"featured_img_caption":"","series_order":"","authors":[{"term_id":40,"user_id":5,"is_guest":0,"slug":"joaodurant","display_name":"Jo\u00e3o Durant","avatar_url":{"url":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-content\/uploads\/2025\/06\/cropped-grupoAB-04-1.jpg","url2x":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-content\/uploads\/2025\/06\/cropped-grupoAB-04-1.jpg"},"author_category":"","first_name":"Jo\u00e3o","last_name":"Durant","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-json\/wp\/v2\/posts\/10815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-json\/wp\/v2\/comments?post=10815"}],"version-history":[{"count":1,"href":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-json\/wp\/v2\/posts\/10815\/revisions"}],"predecessor-version":[{"id":10816,"href":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-json\/wp\/v2\/posts\/10815\/revisions\/10816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-json\/wp\/v2\/media\/10814"}],"wp:attachment":[{"href":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-json\/wp\/v2\/media?parent=10815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-json\/wp\/v2\/categories?post=10815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-json\/wp\/v2\/tags?post=10815"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.cbnrecife.com\/blogdoelielson\/wp-json\/wp\/v2\/ppma_author?post=10815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}